{"id":301056,"date":"2024-07-02T17:06:45","date_gmt":"2024-07-02T20:06:45","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=301056"},"modified":"2024-07-02T17:06:45","modified_gmt":"2024-07-02T20:06:45","slug":"estudante-da-ufla-e-campea-brasileira-na-prova-dos-400-metros-rasos-do-trofeu-brasil-de-atletismo-2024","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/estudante-da-ufla-e-campea-brasileira-na-prova-dos-400-metros-rasos-do-trofeu-brasil-de-atletismo-2024\/","title":{"rendered":"Estudante da UFLA \u00e9 campe\u00e3 brasileira na prova dos 400 metros rasos do Trof\u00e9u Brasil de Atletismo 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">Ja\u00edny Barreto, atleta e estudante do curso de Educa\u00e7\u00e3o F\u00edsica da Universidade Federal de Lavras (UFLA), sagrou-se campe\u00e3 brasileira na prova dos 400 metros rasos durante o Trof\u00e9u Brasil de Atletismo 2024, a maior competi\u00e7\u00e3o interclubes da Am\u00e9rica Latina. As provas da semifinal e da final ocorreram nos dias 27 e 28 de junho, respectivamente, no Centro de Treinamento Paral\u00edmpico Brasileiro (CPB).<\/p>\n<p style=\"text-align: justify;\">Ja\u00edny, integrante do Programa Cria Lavras Atletismo, tamb\u00e9m faz parte do Programa Atleta de Alto Rendimento, promovido pela Pr\u00f3-Reitoria de Apoio \u00e0 Perman\u00eancia Estudantil (Prape\/UFLA). Sua vit\u00f3ria representa um marco significativo tanto para sua carreira esportiva quanto para a institui\u00e7\u00e3o que representa.<\/p>\n<p style=\"text-align: justify;\">Para mais informa\u00e7\u00f5es, acesse ufla.br, confira o link nos stories ou visite o destaque \u201c\u00daltimas Not\u00edcias\u201d no perfil do Instagram @uflabr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ja\u00edny Barreto, atleta e estudante do curso de Educa\u00e7\u00e3o F\u00edsica da Universidade Federal de Lavras (UFLA), sagrou-se campe\u00e3 brasileira na prova dos 400 metros rasos durante o Trof\u00e9u Brasil de Atletismo 2024, a maior competi\u00e7\u00e3o interclubes da Am\u00e9rica Latina. As provas da semifinal e da final ocorreram nos dias 27 e 28 de junho, respectivamente, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":301057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-301056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-1"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2024\/07\/IMG_5056.jpg?fit=1350%2C900&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-1gjK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/301056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=301056"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/301056\/revisions"}],"predecessor-version":[{"id":301058,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/301056\/revisions\/301058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/301057"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=301056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=301056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=301056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}