{"id":250982,"date":"2019-12-03T07:00:11","date_gmt":"2019-12-03T10:00:11","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=250982"},"modified":"2019-12-02T20:51:17","modified_gmt":"2019-12-02T23:51:17","slug":"previsao-de-pagamento-do-13o-de-servidores-deve-ser-anunciada-na-semana-que-vem","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/previsao-de-pagamento-do-13o-de-servidores-deve-ser-anunciada-na-semana-que-vem\/","title":{"rendered":"Previs\u00e3o de pagamento do 13\u00ba de servidores deve ser anunciada na semana que vem"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Em visita \u00e0 Assembleia Legislativa de Minas Gerais na tarde desta segunda-feira (2), o secret\u00e1rio de Estado de Planejamento e Gest\u00e3o, Otto Levy, afirmou que a previs\u00e3o de data para o pagamento do 13\u00ba sal\u00e1rio do funcionalismo mineiro deve ser anunciada na semana que vem, caso o projeto que prev\u00ea a antecipa\u00e7\u00e3o dos receb\u00edveis pelo ni\u00f3bio seja aprovado na pr\u00f3xima quarta-feira (4). Segundo ele, ap\u00f3s a conclus\u00e3o da venda na bolsa, os servidores devem receber o benef\u00edcio em at\u00e9 48h, j\u00e1 que quem compra tem 24 horas para pagar, e as outras 24h \u00e9 o tempo necess\u00e1rio para que o governo do Estado conclua o dep\u00f3sito.<\/p>\n<p style=\"text-align: justify;\">\nConsiderado por deputados, o uso de recursos j\u00e1 existentes em caixa foi descartado pelo secret\u00e1rio, que foi categ\u00f3rico ao afirmar que Minas &#8220;n\u00e3o tem recursos para pagar o 13\u00ba hoje&#8221;. Questionado sobre a possibilidade de a venda n\u00e3o sair conforme esperado, o secret\u00e1rio respondeu dizendo que vai tentar novamente no ano que vem. &#8220;No momento n\u00f3s n\u00e3o temos outra alternativa, n\u00f3s acreditamos que a opera\u00e7\u00e3o vai ser bem-sucedida e estamos trabalhando com essa hip\u00f3tese&#8221;, declarou.<\/p>\n<p style=\"text-align: justify;\">O governo de Minas precisa de R$ 5 bilh\u00f5es para viabilizar o pagamento do 13\u00ba de todos os servidores do Executivo e garantir o fim dos parcelamentos por at\u00e9 sete meses. Desse montante, R$ 3 bilh\u00f5es seriam usados para a folha e outros R$ 2 bilh\u00f5es para compor o caixa e permitir que o pagamento dos sal\u00e1rios seguintes seja feito no quinto dia \u00fatil.<\/p>\n<p style=\"text-align: justify;\">A opera\u00e7\u00e3o inteira, que vai desde a entrega de documentos na bolsa at\u00e9 a realiza\u00e7\u00e3o do leil\u00e3o e o recebimento dos cr\u00e9ditos, pode durar at\u00e9 quatro semanas, conforme a Seplag. Mas Levy afirmou que o governo far\u00e1 o poss\u00edvel para que o 13\u00ba seja pago ainda neste ano.<\/p>\n<p style=\"text-align: justify;\">Opera\u00e7\u00e3o de risco<\/p>\n<p style=\"text-align: justify;\">O Projeto de Lei 1205\/2019, em discuss\u00e3o na ALMG e com segundo turno previsto para esta quarta-feira (4), quer adiantar receb\u00edveis pela explora\u00e7\u00e3o do ni\u00f3bio at\u00e9 2032. Otto Levy esteve na ALMG para responder a questionamentos dos deputados estaduais sobre os riscos da opera\u00e7\u00e3o. Entre as d\u00favidas, foram apontados riscos como a valoriza\u00e7\u00e3o do mineral acima do esperado, o tempo de validade de doze anos, que ultrapassa o mandato do atual governador, o esgotamento dos recursos explor\u00e1veis, entre outros.<\/p>\n<p style=\"text-align: justify;\">Durante o debate na comiss\u00e3o, o titular da Seplag admitiu que o Estado pode, sim, perder dinheiro caso o ni\u00f3bio seja mais valorizado durante os doze anos do que a expectativa aponta, mas que esse \u00e9 um risco que se corre em neg\u00f3cios na Bolsa de Valores. Sobre o tempo de dura\u00e7\u00e3o do contrato, o secret\u00e1rio justificou dizendo que ele foi definido considerando o montante necess\u00e1rio para a regulariza\u00e7\u00e3o dos pagamentos do funcionalismo.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 a respeito dos recursos existentes, Levy citou estudos que apontam que a jazida pode durar por at\u00e9 200 anos. O secret\u00e1rio tamb\u00e9m destacou que n\u00e3o se trata de uma opera\u00e7\u00e3o de cr\u00e9dito e que o Estado s\u00f3 abrir\u00e1 m\u00e3o de 49% dos receb\u00edveis nos pr\u00f3ximos doze anos. &#8220;Minas Gerais recebe 25% dos lucros da explora\u00e7\u00e3o do mineral, deles, 51% vai para a Codemge e 49% vai para a Codemig, e \u00e9 desses 49% que vamos adiantar os receb\u00edveis&#8221;, explicou, reiterando que o Estado continuar\u00e1 com lucro vindo atrav\u00e9s da Codemge.<\/p>\n<p style=\"text-align: justify;\">\nO pre\u00e7o m\u00ednimo para o leil\u00e3o ainda n\u00e3o foi definido, conforme declarou o secret\u00e1rio, e deve ser calculado levando em considera\u00e7\u00e3o vari\u00e1veis como plano de produ\u00e7\u00e3o futuro, capacidade de produ\u00e7\u00e3o, proje\u00e7\u00e3o de pre\u00e7os e produtos, taxa de c\u00e2mbio e volume de vendas, al\u00e9m de uma an\u00e1lise hist\u00f3rica. &#8220;Se eu falar quanto eu espero que seja o valor m\u00ednimo eu vou estar ancorando as expectativas e indo contra os interesses do Estado de Minas Gerais&#8221;, justificou Levy.<\/p>\n<p style=\"text-align: justify;\">Substitutivo<\/p>\n<p style=\"text-align: justify;\">As comiss\u00f5es de Minas e Energia e Administra\u00e7\u00e3o P\u00fablica apresentar\u00e3o nesta ter\u00e7a-feira (3) um substitutivo para blindar o Estado de poss\u00edveis entraves jur\u00eddicos referentes \u00e0 explora\u00e7\u00e3o do ni\u00f3bio. Membro da Comiss\u00e3o de Minas e Energia, o deputado Jo\u00e3o Vitor Xavier (Cidadania) declarou que o projeto veio do governo como uma &#8220;carta de inten\u00e7\u00f5es&#8221;, sem o devido detalhamento explicando como a opera\u00e7\u00e3o seria realizada. &#8220;Nosso objetivo \u00e9 resguardar o direito do Estado, do povo de Minas Gerais e o pr\u00f3prio governo reconheceu a raz\u00e3o da Assembleia nesses questionamentos&#8221;, defendeu.<\/p>\n<p style=\"text-align: justify;\">Uma das defini\u00e7\u00f5es do substitutivo visa bloquear para o Estado o direito de qualquer a\u00e7\u00e3o judicial. &#8220;Existe, hoje, um lit\u00edgio de R$ 5 bilh\u00f5es entre o Estado e a CBMM, e queremos assegurar que o dinheiro n\u00e3o v\u00e1 para o investidor em caso de vit\u00f3ria do Estado&#8221;, explicou Xavier.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonte: Daniele Franco\/Hoje em Dia\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Em visita \u00e0 Assembleia Legislativa de Minas Gerais na tarde desta segunda-feira (2), o secret\u00e1rio de Estado de Planejamento e Gest\u00e3o, Otto Levy, afirmou que a previs\u00e3o de data para o pagamento do 13\u00ba sal\u00e1rio do funcionalismo mineiro deve ser anunciada na semana que vem, caso o projeto que prev\u00ea a antecipa\u00e7\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":238664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-250982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-1"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2018\/11\/2-1.jpg?fit=500%2C300&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-13i6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/250982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=250982"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/250982\/revisions"}],"predecessor-version":[{"id":250983,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/250982\/revisions\/250983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/238664"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=250982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=250982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=250982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}