{"id":249802,"date":"2019-10-23T07:00:12","date_gmt":"2019-10-23T10:00:12","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=249802"},"modified":"2019-10-22T13:51:28","modified_gmt":"2019-10-22T16:51:28","slug":"sesc-lavras-inaugura-sua-nova-unidade-nesta-quinta-feira-24","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/sesc-lavras-inaugura-sua-nova-unidade-nesta-quinta-feira-24\/","title":{"rendered":"Sesc Lavras inaugura sua nova unidade nesta quinta-feira (24)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">O Servi\u00e7o Social do Com\u00e9rcio (Sesc) vai inaugurar a sua nova unidade em lavras nesta quinta-feira, dia 24, \u00e0s 19h30. Ela fica localizada na rua Misseno de P\u00e1dua, 831, centro.<\/p>\n<p style=\"text-align: justify;\">A cerimonia contar\u00e1 com a presen\u00e7a do presidente dos Conselhos Regionais do Sesc e do Senac em Minas, Francisco Valdeci de Souza Cavalcante. A nova unidade come\u00e7ou a funcionar no dia 30 de setembro<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m dos servi\u00e7os j\u00e1 oferecidos, como a venda de pacotes de excurs\u00f5es, hospedagens e emiss\u00e3o do cart\u00e3o do cliente, o Sesc Lavras traz duas novidades: o Sesc Fitness, uma academia ampla e climatizada, que conta com equipamentos de \u00faltima gera\u00e7\u00e3o, profissionais qualificados e pre\u00e7os diferenciados; e o Cria Sesc, uma evolu\u00e7\u00e3o do Projeto Habilidades de Estudo (PHE), que prop\u00f5e o desenvolvimento al\u00e9m da escola, com base na viv\u00eancia e na experimenta\u00e7\u00e3o do aluno no contraturno escolar.<\/p>\n<p style=\"text-align: justify;\">A amplia\u00e7\u00e3o para uma estrutura maior e mais moderna permite ao Sesc em Minas oferecer mais servi\u00e7os e um melhor atendimento. De acordo com Caio M\u00e1rcio Goulart, presidente do Sindicato do Com\u00e9rcio de Lavras, a popula\u00e7\u00e3o s\u00f3 tem a ganhar.<\/p>\n<p style=\"text-align: justify;\"><strong>Sobre<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Academia Sesc Fitness<\/strong>: com 206m\u00b2, o espa\u00e7o \u00e9 climatizado e conta com equipamentos de \u00faltima gera\u00e7\u00e3o, profissionais qualificados, al\u00e9m de pre\u00e7os diferenciados. Os planos custam a partir de R$ 37,50 (para trabalhadores do com\u00e9rcio de bens, servi\u00e7os e turismo e seus dependentes). A atividade come\u00e7a a funcionar no dia 7 de outubro.<\/p>\n<p style=\"text-align: justify;\"><strong>Cria Sesc<\/strong>: na nova estrutura, al\u00e9m do acompanhamento pedag\u00f3gico e de atividades extracurriculares, as crian\u00e7as inscritas no Cria Sesc contar\u00e3o com o Espa\u00e7o Cria, um ambiente com um conceito novo de ci\u00eancia e experimenta\u00e7\u00f5es, onde tamb\u00e9m ser\u00e3o realizadas as atividades de express\u00e3o corporal. O espa\u00e7o tamb\u00e9m disp\u00f5e de uma biblioteca exclusiva para uso dos alunos. No Cria Sesc, todas as necessidades de desenvolvimento das crian\u00e7as ser\u00e3o atendidas, de forma integral, por meio de atividades complementares ao ensino formal. O objetivo \u00e9 que realizem cada vez mais trabalhos voltados para a cultura maker (fa\u00e7a voc\u00ea mesmo) em que s\u00e3o estimuladas a fazer com as pr\u00f3prias m\u00e3os.<\/p>\n<p style=\"text-align: justify;\">Com o novo Sesc Lavras, o Sesc em Minas, que est\u00e1 presente nos quatro cantos do estado, se aproxima ainda mais da popula\u00e7\u00e3o da regi\u00e3o, oferecendo maior excel\u00eancia nos servi\u00e7os e no atendimento ao p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0 O Servi\u00e7o Social do Com\u00e9rcio (Sesc) vai inaugurar a sua nova unidade em lavras nesta quinta-feira, dia 24, \u00e0s 19h30. Ela fica localizada na rua Misseno de P\u00e1dua, 831, centro. A cerimonia contar\u00e1 com a presen\u00e7a do presidente dos Conselhos Regionais do Sesc e do Senac em Minas, Francisco Valdeci de Souza Cavalcante. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":249803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,4],"tags":[],"class_list":["post-249802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-1","category-lavras"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/10\/DSC_0571-1.jpg?fit=600%2C400&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-12Z4","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/249802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=249802"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/249802\/revisions"}],"predecessor-version":[{"id":249804,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/249802\/revisions\/249804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/249803"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=249802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=249802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=249802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}