{"id":245222,"date":"2019-05-31T11:37:55","date_gmt":"2019-05-31T14:37:55","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=245222"},"modified":"2019-05-31T11:37:55","modified_gmt":"2019-05-31T14:37:55","slug":"pmmg-realiza-seminario-de-prevencao-a-violencia-domestica","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/pmmg-realiza-seminario-de-prevencao-a-violencia-domestica\/","title":{"rendered":"PMMG realiza Semin\u00e1rio de Preven\u00e7\u00e3o \u00e0 Viol\u00eancia Dom\u00e9stica"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">De 20 \u00e0 25 de maio aconteceu o Semin\u00e1rio de Preven\u00e7\u00e3o \u00e0 Viol\u00eancia Dom\u00e9stica, planejado pela PMMG, em Varginha representada pelo 24\u00b0 BPM, cujo principal objetivo foi o envolvimento dos diversos \u00f3rg\u00e3os que comp\u00f5em a Rede de enfrentamento e uma maior conscientiza\u00e7\u00e3o a fim de identificar meios de quebrar o ciclo da viol\u00eancia contra a mulher, protegendo a v\u00edtima e impedindo novas agress\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Essa \u00e9 uma quest\u00e3o que vai muito al\u00e9m das p<span class=\"text_exposed_show\">rovid\u00eancias policiais, antes perpassa pela fam\u00edlia, a cria\u00e7\u00e3o dos filhos e a educa\u00e7\u00e3o. Por isso destacamos qu\u00e3o valiosa foi a participa\u00e7\u00e3o dos jovens estudantes das diversas faculdades do munic\u00edpio, que podem, atrav\u00e9s de uma conscientiza\u00e7\u00e3o, portar-se de maneira diferente frente a esta quest\u00e3o, seja em sua vida pessoal ou profissional.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p style=\"text-align: justify;\">Tivemos v\u00e1rias atividades como blitz educativa com distribui\u00e7\u00e3o de dicas de seguran\u00e7a, palestras no Teatro Mestrinho com a Comandante da 1\u00b0 Companhia de Preven\u00e7\u00e3o \u00e0 Viol\u00eancia Dom\u00e9stica, Major Cleide, a MM Ju\u00edza Dra Mara\u00edsa, a Dra T\u00e2nit e o Dr Oilson, sobre temas relevantes , estat\u00edsticas, reflex\u00e3o e partilha de conhecimento; tivemos workshop sobre o atendimento de ocorr\u00eancia, apresenta\u00e7\u00e3o da Banda de M\u00fasica da 6\u00b0 RPM, estandes de estudantes, palestra em faculdades e encerrando com a caminhada pelo fim da viol\u00eancia dom\u00e9stica.<\/p>\n<p style=\"text-align: justify;\">O 24\u00b0 BPM agradece o apoio de todos que de alguma forma, contribu\u00edram para que fosse poss\u00edvel essa discuss\u00e3o, t\u00e3o urgente, especialmente a Rede de Enfrentamento \u00e0 Viol\u00eancia Dom\u00e9stica, pois juntos somos mais fortes.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; De 20 \u00e0 25 de maio aconteceu o Semin\u00e1rio de Preven\u00e7\u00e3o \u00e0 Viol\u00eancia Dom\u00e9stica, planejado pela PMMG, em Varginha representada pelo 24\u00b0 BPM, cujo principal objetivo foi o envolvimento dos diversos \u00f3rg\u00e3os que comp\u00f5em a Rede de enfrentamento e uma maior conscientiza\u00e7\u00e3o a fim de identificar meios de quebrar o ciclo da viol\u00eancia contra [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":245223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,4],"tags":[467,466],"class_list":["post-245222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-1","category-lavras","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/61596595_1098312727037905_5900721006649016320_n.jpg?fit=500%2C375&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11Nc","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=245222"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245222\/revisions"}],"predecessor-version":[{"id":245224,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245222\/revisions\/245224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/245223"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=245222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=245222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=245222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}