{"id":245116,"date":"2019-05-27T17:15:56","date_gmt":"2019-05-27T20:15:56","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=245116"},"modified":"2019-05-27T17:15:56","modified_gmt":"2019-05-27T20:15:56","slug":"lavrenses-ja-estao-sendo-beneficiados-com-nova-ponte-branca","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/lavrenses-ja-estao-sendo-beneficiados-com-nova-ponte-branca\/","title":{"rendered":"Lavrenses j\u00e1 est\u00e3o sendo beneficiados com Nova Ponte Branca"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">Nos \u00faltimos 8 meses, o Governo Municipal de Lavras trabalhou incansavelmente para entregar aos lavrenses uma Nova Ponte Branca. A obra foi finalizada antes do cronograma, que era de 9 meses, e entregue \u00e0 comunidade no s\u00e1bado, dia 18.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">Centenas de pessoas participaram da solenidade de inaugura\u00e7\u00e3o, que contou com a participa\u00e7\u00e3o do chefe do Executivo, vice-prefeito e diversas autoridades de Lavras e a regi\u00e3o. Tamb\u00e9m contou com apresenta\u00e7\u00f5es da Banda Euterpe Oper\u00e1ria, Percuss\u00e3o com Instrumentos de Materiais Recicl\u00e1veis do Projeto Semearte, alunos da Rede Municipal de Ensino, Fanfarra da Escola Municipal \u00c1lvaro Botelho, Clube de Ve\u00edculos Antigos de Lavras (CVAL), Jeepeiros e Moto Grupos.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">\u201cA obra foi realizada por R$ 1.289.521,71, or\u00e7amento exclusivo do munic\u00edpio e sem nenhum aditivo. Ela foi bem pensada, planejada e trabalhada. \u00c9 o recurso do cidad\u00e3o de Lavras retornando para que possa melhorar toda uma regi\u00e3o e o entorno. O que mais nos movimentou foi a falta de seguran\u00e7a dos pedestres ao transitarem pela ponte, m\u00e3es tinham que colocar o carrinhos das crian\u00e7as na rua e disputar espa\u00e7o com \u00f4nibus, caminh\u00f5es e outros ve\u00edculos. Como o Vila Rica, v\u00e1rios bairros de Lavras foram constru\u00eddos sem planejamento eficaz de infraestrutura. Mas estamos trabalhando para mudar isso\u201d, disse o prefeito de Lavras na solenidade.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">A Ponte Branca foi constru\u00edda no s\u00e9culo passado, em uma \u00e9poca em que a regi\u00e3o possu\u00eda fazendas e estradas de terra, servindo de liga\u00e7\u00e3o entre a zona rural e urbana. Com o passar do tempo a ponte ficou em meio \u00e0 cidade, recebendo um grande volume de ve\u00edculos e pedestres. Mas nenhuma reforma foi realizada, ainda sendo de pista \u00fanica e com passeios inadequados. Por mais de 40 anos, foi um anseio da popula\u00e7\u00e3o sua duplica\u00e7\u00e3o.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">A espera acabou. Imediatamente ap\u00f3s a entrega, os lavrenses j\u00e1 come\u00e7aram a desfrutar de todos os benef\u00edcios da obra. \u00c9 a concretiza\u00e7\u00e3o do compromisso da administra\u00e7\u00e3o municipal no uso do dinheiro p\u00fablico em prol da popula\u00e7\u00e3o.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><b>Os benef\u00edcios n\u00e3o acabam, ficam para as novas gera\u00e7\u00f5es<\/b><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">Esta obra \u00e9 uma grande materializa\u00e7\u00e3o de uma s\u00e9rie de a\u00e7\u00f5es do programa de reestrutura\u00e7\u00e3o da mobilidade e infraestrutura da cidade de Lavras.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">A obra ir\u00e1 trazer mais seguran\u00e7a para os pedestres, que poder\u00e3o passar dos dois lados da ponte, sem desvios em seu trajeto. Foram instalados guarda-corpos dos dois lados das passagens, na divis\u00e3o com os carros e na extremidade da ponte com estrutura \u201canti-suic\u00eddio\u201d. <\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">A obra foi pensada pelos engenheiros e arquitetos para tamb\u00e9m trazer um embelezamento arquitet\u00f4nico para a cidade. As cores e tra\u00e7os s\u00e3o pensados para misturarem-se com a paisagem, e o entorno recebeu grama. A Rua Nan\u00e1 de P\u00e1dua recebeu nova pavimenta\u00e7\u00e3o, sinaliza\u00e7\u00e3o e l\u00e2mpadas LED, nova tecnologia que ilumina mais e \u00e9 econ\u00f4mica e dur\u00e1vel.<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">Outro grande benef\u00edcio s\u00e3o os avan\u00e7os para a mobilidade urbana, que ter\u00e3o reflexos diretos na zona sul, leste e centro. A ponte liga as regi\u00f5es sul e leste, e \u00e9 uma op\u00e7\u00e3o para quem passa por uma das principais vias da cidade, a Av. Sylvio Menicucci. Sem dificuldades no tr\u00e2nsito toda a localidade est\u00e1 preparada para mais desenvolvimento!<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><b><i>*Diretoria de Comunica\u00e7\u00e3o Social \u2013 Governo Municipal de Lavras<\/i><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Nos \u00faltimos 8 meses, o Governo Municipal de Lavras trabalhou incansavelmente para entregar aos lavrenses uma Nova Ponte Branca. A obra foi finalizada antes do cronograma, que era de 9 meses, e entregue \u00e0 comunidade no s\u00e1bado, dia 18. Centenas de pessoas participaram da solenidade de inaugura\u00e7\u00e3o, que contou com a participa\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":245117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13077,4],"tags":[467,466],"class_list":["post-245116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-2","category-lavras","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/4Copia.jpg?fit=500%2C281&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11Lu","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=245116"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245116\/revisions"}],"predecessor-version":[{"id":245118,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245116\/revisions\/245118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/245117"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=245116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=245116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=245116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}