{"id":245113,"date":"2019-05-27T17:11:32","date_gmt":"2019-05-27T20:11:32","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=245113"},"modified":"2019-05-27T17:11:32","modified_gmt":"2019-05-27T20:11:32","slug":"ufla-arrecada-pilhas-para-reciclagem","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/ufla-arrecada-pilhas-para-reciclagem\/","title":{"rendered":"UFLA arrecada pilhas para reciclagem"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">At\u00e9 o dia 27\/6, a Universidade Federal de Lavras (UFLA) realiza uma mobiliza\u00e7\u00e3o junto \u00e0 comunidade acad\u00eamica para coleta de pilhas e destina\u00e7\u00e3o \u00e0 reciclagem. Os respons\u00e1veis pelos departamentos e setores administrativos da Institui\u00e7\u00e3o devem entregar o material coletado no pr\u00e9dio da Diretoria de Meio Ambiente (DMA).<\/p>\n<p style=\"text-align: justify;\">A a\u00e7\u00e3o faz parte de um conjunto de medidas desenvolvidas pelo setor para aprimorar os processos de reciclagem no c\u00e2mpus, que inclu\u00edram tamb\u00e9m a\u00a0<a href=\"https:\/\/ufla.br\/noticias\/institucional\/12889-novas-lixeiras-no-campus-facilitam-processo-de-reciclagem\">instala\u00e7\u00e3o de 80 conjuntos de lixeiras de recicl\u00e1veis e n\u00e3o-recicl\u00e1veis<\/a>, e de coletores de pilhas \u00a0no Pavilh\u00e3o 3 e nas cantinas do Departamento de Medicina Veterin\u00e1ria e do Departamento de Ci\u00eancias Humanas, al\u00e9m da j\u00e1 existente no Centro de Conviv\u00eancia, ao lado da Copy Uai.<\/p>\n<p style=\"text-align: justify;\">As pilhas cont\u00e9m metal pesado e devem ser descartadas seguindo uma pol\u00edtica de log\u00edstica reversa, retornando o produto ao fabricante para que seja feita a destina\u00e7\u00e3o correta do res\u00edduo. Assim, o programa de coleta seletiva depende de uma segrega\u00e7\u00e3o adequada dos res\u00edduos na fonte geradora.<\/p>\n<p style=\"text-align: justify;\">Quando descartadas de maneira inadequada, as pilhas causam degrada\u00e7\u00e3o ao meio ambiente e preju\u00edzos \u00e0 sa\u00fade humana e \u00e0 natureza. Os res\u00edduos possuem zinco, chumbo e mangan\u00eas em sua forma\u00e7\u00e3o, al\u00e9m de outras \u00a0subst\u00e2ncias como o merc\u00fario, o c\u00e1dmio e o cloreto de am\u00f4nia que podem contaminar o solo, a \u00e1gua, animais e causar doen\u00e7as aos seres humanos. A reciclagem desse tipo de produto garante mais qualidade ao lixo encontrado nos aterros sanit\u00e1rios.<\/p>\n<h3 style=\"text-align: justify;\">Algumas dicas sobre o uso correto de pilhas e baterias:<\/h3>\n<p style=\"text-align: justify;\">&#8211; Ao adquirir pilhas e baterias, prefira as recarreg\u00e1veis ou alcalinas. Elas t\u00eam maior durabilidade.<\/p>\n<p style=\"text-align: justify;\">&#8211; N\u00e3o misture pilhas diferentes (alcalinas e comuns, novas e usadas), pois isto compromete o desempenho e a durabilidade do produto. Ao fazer a substitui\u00e7\u00e3o nos aparelhos, troque todas ao mesmo tempo;<\/p>\n<p style=\"text-align: justify;\">&#8211; Ao deixar um aparelho por um longo tempo sem uso, retire as pilhas ou baterias pois podem vazar;<\/p>\n<p style=\"text-align: justify;\">&#8211; N\u00e3o tente abrir pilhas e baterias, e n\u00e3o as exponha ao calor excessivo ou \u00e0 umidade, por elas podem explodir ou vazar;<\/p>\n<p style=\"text-align: justify;\">&#8211; Nunca guarde pilhas e baterias junto a brinquedos, alimentos ou rem\u00e9dios e n\u00e3o as descarte no meio ambiente;<\/p>\n<p style=\"text-align: justify;\">&#8211; N\u00e3o use pilhas e baterias piratas.<\/p>\n<p style=\"text-align: justify;\">Mais informa\u00e7\u00f5es sobre a coleta de pilhas junto \u00e0 DMA, pelo (35) 3829-9779 ou\u00a0<span id=\"cloak981fc0c54cd8afe5a32d582a52c512f0\"><a href=\"mailto:dma@ufla.br\">dma@ufla.br<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; At\u00e9 o dia 27\/6, a Universidade Federal de Lavras (UFLA) realiza uma mobiliza\u00e7\u00e3o junto \u00e0 comunidade acad\u00eamica para coleta de pilhas e destina\u00e7\u00e3o \u00e0 reciclagem. Os respons\u00e1veis pelos departamentos e setores administrativos da Institui\u00e7\u00e3o devem entregar o material coletado no pr\u00e9dio da Diretoria de Meio Ambiente (DMA). A a\u00e7\u00e3o faz parte de um [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":245114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,4],"tags":[467,466],"class_list":["post-245113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-2","category-lavras","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/close-up-de-um-mao-mulher-segurando-verde-baterias_23-2147839003.jpg?fit=500%2C333&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11Lr","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=245113"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245113\/revisions"}],"predecessor-version":[{"id":245115,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245113\/revisions\/245115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/245114"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=245113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=245113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=245113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}