{"id":245083,"date":"2019-05-26T13:30:30","date_gmt":"2019-05-26T16:30:30","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=245083"},"modified":"2019-05-26T13:30:30","modified_gmt":"2019-05-26T16:30:30","slug":"massa-de-ar-frio-chega-a-minas-e-provoca-novo-recorde-de-temperatura-baixa","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/massa-de-ar-frio-chega-a-minas-e-provoca-novo-recorde-de-temperatura-baixa\/","title":{"rendered":"Massa de ar frio chega a Minas e provoca novo recorde de temperatura baixa"},"content":{"rendered":"<div><\/div>\n<div><\/div>\n<div>A chegada de uma massa de ar frio a Minas Gerais, prevista nesta semana, resultou em mais um recorde de temperatura baixa no estado. Neste domingo, a temperatura m\u00ednima em Maria da F\u00e9, no Sul de Minas Gerais, chegou a 3\u00b0C, a menor do ano, segundo o Instituto Nacional de Meteorologia (Inmet). O recorde anterior foi registrado em Monte Verde na \u00faltima quarta-feira, quando foram registrados 4,4\u00b0C. Houve geada fraca em alguns pontos da regi\u00e3o Sul e Campo das Vertentes nesta manh\u00e3.<\/div>\n<div><\/div>\n<div>Na tarde de s\u00e1bado, a Defesa Civil de Belo Horizonte j\u00e1 havia divulgado um alerta de temperatura baixa at\u00e9 a segunda-feira. Neste s\u00e1bado, segundo o meteorologista Jorge Luiz Moreira, do Inmet, a menor temperatura registrada em Belo Horizonte hoje foi de 13,9\u00b0C na Pampulha. Ontem, na mesma esta\u00e7\u00e3o meteorol\u00f3gica, os term\u00f4metros haviam marcado 16,3\u00b0C. Hoje, na esta\u00e7\u00e3o do Cercadinho, na Regi\u00e3o Oeste, a m\u00ednima foi 14,8\u00b0C, e 15\u00b0C no Santo Agostinho.<\/div>\n<div>\n<div class=\"img-mobile-full mb-20\"><\/div>\n<\/div>\n<div>O sistema \u00e9 o primeiro que atingiu o estado na segunda semana de maio, cujo clima t\u00edpico \u00e9 de calor durante o dia e frio \u00e0 noite. \u201cEsta massa ainda vai atuar na pr\u00f3xima madrugada. As temperaturas v\u00e3o continuar baixas e ao longo da semana gradualmente ela perde for\u00e7a. Haver\u00e1 uma ligeira eleva\u00e7\u00e3o das m\u00ednimas a partir de ter\u00e7a\u201d, informou Moreira.<\/div>\n<div><\/div>\n<div>A tend\u00eancia para a semana \u00e9 de tempo est\u00e1vel e seco.\u00a0 Nas regi\u00f5es do Tri\u00e2ngulo Mineiro, Noroeste, Oeste Central e Metropolitana, a umidade relativa do ar pode chegar a \u00edndices inferiores a 30% \u00e0 tarde.<\/div>\n<div><\/div>\n<div>Fonte: Cristiane Silva\/Portal Uai<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A chegada de uma massa de ar frio a Minas Gerais, prevista nesta semana, resultou em mais um recorde de temperatura baixa no estado. Neste domingo, a temperatura m\u00ednima em Maria da F\u00e9, no Sul de Minas Gerais, chegou a 3\u00b0C, a menor do ano, segundo o Instituto Nacional de Meteorologia (Inmet). O recorde anterior [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":245084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13],"tags":[467,466],"class_list":["post-245083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-1","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/20190526111816943007a.jpeg?fit=600%2C297&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11KX","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=245083"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245083\/revisions"}],"predecessor-version":[{"id":245085,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/245083\/revisions\/245085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/245084"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=245083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=245083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=245083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}