{"id":244962,"date":"2019-05-21T13:11:12","date_gmt":"2019-05-21T16:11:12","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=244962"},"modified":"2019-05-21T13:11:12","modified_gmt":"2019-05-21T16:11:12","slug":"operacao-contencao-da-policia-militar-sacode-campo-belo","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/operacao-contencao-da-policia-militar-sacode-campo-belo\/","title":{"rendered":"Opera\u00e7\u00e3o &#8220;Conten\u00e7\u00e3o&#8221; da Pol\u00edcia Militar sacode Campo Belo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ter\u00e7a-feira (21), a Pol\u00edcia Militar desencadeou uma opera\u00e7\u00e3o repressiva na cidade de Campo Belo. Cerca de 40 Policiais Militares cumpriram 5 mandados de busca e apreens\u00e3o, prendendo 2 traficantes que agiam na cidade.<\/p>\n<p>Foram apreendidas durante a opera\u00e7\u00e3o grande quantidade de drogas, R$2856,00 e v\u00e1rias anota\u00e7\u00f5es da movimenta\u00e7\u00e3o do tr\u00e1fico de drogas.<\/p>\n<div class=\"text_exposed_show\">\n<p>Um dos infratores estava envolvido em diversos roubos e articulava uma organiza\u00e7\u00e3o criminosa na cidade.<\/p>\n<p>J\u00e1 o segundo infrator figurava como gerente do tr\u00e1fico de drogas no bairro S\u00e3o Benedito. A droga apreendida estava escondida em uma mata em frente sua resid\u00eancia.<\/p>\n<p>Ela seria suficiente para abastecer outros pontos de venda de entorpecentes na cidade.<\/p>\n<p>Foram apreendidos ainda 10 p\u00e1ssaros da fauna silvestre, gaiolas e al\u00e7ap\u00f5es, al\u00e9m de anilhas adulteradas.<\/p>\n<p>A PM do Meio Ambiente aplicou mais de R$20.000,00 em autua\u00e7\u00f5es pelos pelas infra\u00e7\u00f5es constatadas.<\/p>\n<p>Ao todo foram apreendidos 4.450 papelotes de coca\u00edna, 12 tabletes de maconha, 38 buchas de maconha e 400 pedras de crack.<\/p>\n<p>A opera\u00e7\u00e3o continua em andamento, sendo que os militares est\u00e3o distribu\u00eddos em toda a cidade, realizando abordagens e a\u00e7\u00f5es preventivas.<\/p>\n<p>ACO\/8\u00baBPM<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ter\u00e7a-feira (21), a Pol\u00edcia Militar desencadeou uma opera\u00e7\u00e3o repressiva na cidade de Campo Belo. Cerca de 40 Policiais Militares cumpriram 5 mandados de busca e apreens\u00e3o, prendendo 2 traficantes que agiam na cidade. Foram apreendidas durante a opera\u00e7\u00e3o grande quantidade de drogas, R$2856,00 e v\u00e1rias anota\u00e7\u00f5es da movimenta\u00e7\u00e3o do tr\u00e1fico de drogas. Um dos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":244963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,79],"tags":[467,466],"class_list":["post-244962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-1","category-regiao","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/60617128_1263799393773034_8386095491376480256_o.jpg?fit=500%2C281&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11J0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=244962"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244962\/revisions"}],"predecessor-version":[{"id":244964,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244962\/revisions\/244964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/244963"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=244962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=244962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=244962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}