{"id":244864,"date":"2019-05-17T17:38:22","date_gmt":"2019-05-17T20:38:22","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=244864"},"modified":"2019-05-17T17:38:22","modified_gmt":"2019-05-17T20:38:22","slug":"nova-ponte-branca-sera-inaugurada-neste-sabado-18","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/nova-ponte-branca-sera-inaugurada-neste-sabado-18\/","title":{"rendered":"Nova Ponte Branca ser\u00e1 inaugurada neste s\u00e1bado (18)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">A Nova Ponte Branca ser\u00e1 entregue \u00e0 popula\u00e7\u00e3o neste s\u00e1bado, dia 18. A obra foi totalmente realizada com recursos pr\u00f3prios do Governo Municipal de Lavras no valor de R$ 1.289.521,71. Toda a popula\u00e7\u00e3o est\u00e1 convidada para a solenidade de inaugura\u00e7\u00e3o \u00e0s 9h.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Todos que conhecem o local entendem a import\u00e2ncia desta obra, um grande anseio dos lavrenses h\u00e1 mais de quarenta anos. Constru\u00edda no s\u00e9culo passado, a ponte servia de liga\u00e7\u00e3o de comunidades rurais com a cidade. Com o passar do tempo e o desenvolvimento da regi\u00e3o a ponte ficou na zona urbana, recebendo um grande volume de ve\u00edculos, apesar de ser estreita e permitir a passagem de apenas um por vez, al\u00e9m de n\u00e3o ser segura para os pedestres. Passaram-se anos sem que nada fosse feito, mas agora todos que transitam por ela poder\u00e3o contar com a duplica\u00e7\u00e3o e uma s\u00e9rie de melhorias.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">A obra ir\u00e1 trazer mais seguran\u00e7a para os pedestres, que poder\u00e3o passar dos dois lados da ponte, sem desvios em seu trajeto. Foram instalados guarda-corpos dos dois lados das passagens, na divis\u00e3o com os carros e na extremidade da ponte com estrutura \u201canti-suic\u00eddio\u201d.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Outro grande benef\u00edcio s\u00e3o os avan\u00e7os na mobilidade urbana, que ter\u00e3o reflexos diretos na zona sul, leste e centro. A ponte liga as regi\u00f5es sul e leste, e \u00e9 uma op\u00e7\u00e3o para quem passa por uma das principais vias da cidade, a Av. Sylvio Menicucci. Sem contar que as dificuldades no tr\u00e2nsito tamb\u00e9m interferem no desenvolvimento da localidade.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Esta obra \u00e9 uma grande materializa\u00e7\u00e3o de uma s\u00e9rie de a\u00e7\u00f5es do programa de reestrutura\u00e7\u00e3o da mobilidade e infraestrutura da cidade de Lavras. Nos \u00faltimos dois anos, j\u00e1 foram gastos mais de um milh\u00e3o e meio de reais em obras de drenagem, foram totalmente recapeadas mais de 25 ruas, al\u00e9m do continuo trabalho de limpeza urbana e revitaliza\u00e7\u00e3o de vias p\u00fablicas.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">A obra ser\u00e1 entregue dentro do cronograma estabelecido, sem atrasos. \u00c9 um compromisso da administra\u00e7\u00e3o municipal no uso do dinheiro p\u00fablico em prol da popula\u00e7\u00e3o!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; A Nova Ponte Branca ser\u00e1 entregue \u00e0 popula\u00e7\u00e3o neste s\u00e1bado, dia 18. A obra foi totalmente realizada com recursos pr\u00f3prios do Governo Municipal de Lavras no valor de R$ 1.289.521,71. Toda a popula\u00e7\u00e3o est\u00e1 convidada para a solenidade de inaugura\u00e7\u00e3o \u00e0s 9h. Todos que conhecem o local entendem a import\u00e2ncia desta obra, um [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":244787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14,4],"tags":[467,466],"class_list":["post-244864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-2","category-lavras","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/57101549_613935992454708_8325718816814268416_o.jpg?fit=500%2C281&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11Hq","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=244864"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244864\/revisions"}],"predecessor-version":[{"id":244865,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244864\/revisions\/244865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/244787"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=244864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=244864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=244864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}