{"id":244830,"date":"2019-05-16T13:13:08","date_gmt":"2019-05-16T16:13:08","guid":{"rendered":"https:\/\/www.lavras24horas.com.br\/portal\/?p=244830"},"modified":"2019-05-16T13:13:08","modified_gmt":"2019-05-16T16:13:08","slug":"desemprego-em-minas-cresce-no-primeiro-trimestre-do-ano","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/desemprego-em-minas-cresce-no-primeiro-trimestre-do-ano\/","title":{"rendered":"Desemprego em Minas cresce no primeiro trimestre do ano"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A taxa de desemprego cresceu em 14 das 27 unidades da Federa\u00e7\u00e3o no primeiro trimestre deste ano, na compara\u00e7\u00e3o com o \u00faltimo trimestre do ano passado, segundo dados da Pesquisa Nacional por Amostra de Domic\u00edlios \u2013 Cont\u00ednua (PNAD-C), divulgada nesta quinta-feira pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Minas Gerais est\u00e1 entre os estados que registou esta alta. No trimestre de novembro a dezembro de 2018, a taxa de desemprego no estado era de 9,7% e subiu para 11,2% no primeiro tirmestre deste ano.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de Minas, Acre, Goi\u00e1s, Mato Grosso do Sul, Maranh\u00e3o, Mato Grosso, Distrito Federal, Tocantis, Espirito Santo, Par\u00e1, Cear\u00e1, S\u00e3o Paulo, Paran\u00e1 e Santa Caratina tamb\u00e9m registraram alta. Destes, a maior taxa foi verificada no Acre, que subiu de 13,1% para 18%. Nas outras 13 unidades da federa\u00e7\u00e3o, a taxa manteve-se est\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">Na compara\u00e7\u00e3o com o primeiro trimestre de 2018, no entanto, apenas quatro unidades da Federa\u00e7\u00e3o tiveram aumento da taxa de desemprego.<\/p>\n<p style=\"text-align: justify;\">Na passagem do \u00faltimo trimestre de 2018 para o primeiro trimestre deste ano, as maiores altas da taxa de desemprego foram observadas no Acre (de 13,1% para 18%), Goi\u00e1s (de 8,2% para 10,7%) e Mato Grosso do Sul (de 7% para 9,5%).<\/p>\n<p style=\"text-align: justify;\">\nNa compara\u00e7\u00e3o com o primeiro trimestre de 2018, os estados que registraram alta na taxa foram Roraima (de 10,3% para 15%), Acre (de 14,4% para 18%), Amazonas (de 13,9% para 14,9%) e Santa Catarina (de 6,5% para 7,2%).<\/p>\n<p style=\"text-align: justify;\">J\u00e1 os estados que tiveram queda na taxa, nesse tipo de compara\u00e7\u00e3o, foram Pernambuco (de 17,7% para 16,1%), Minas Gerais (de 12,6% para 11,2%) e Cear\u00e1 (de 12,8% para 11,4%).<\/p>\n<p style=\"text-align: justify;\"><strong>Caracter\u00edstica dos desocupados<\/strong><\/p>\n<p style=\"text-align: justify;\">A pesquisa do IBGE informa tamb\u00e9m o sexo, idade, n\u00edvel de instru\u00e7\u00e3o, al\u00e9m da cor ou ra\u00e7a da popula\u00e7\u00e3o desocupada no Brasil. As mulheres s\u00e3o 52,6% e os homens correspondem a 47,4%. A popula\u00e7\u00e3o de 25 a 59 anos representa 57,2% dos desocupados. Os jovens de 18 a 24, 31,8%, os menores de idade, 8,3% e os idosos, 2,6%.<\/p>\n<p style=\"text-align: justify;\">Quanto a cor ou ra\u00e7a, a pesquisa mostra que 51,2% dos descoupados eram pardos; 35,2%, brancos e 12,7%, pretos.<\/p>\n<p style=\"text-align: justify;\">O n\u00edvel de instru\u00e7\u00e3o aponta que 39% dos descoupados tinham ensino m\u00e9dio completo; 24,4%, fundamental incompleto; 12,5%, m\u00e9dio incompleto; 10,4%, superior completo; 7%, superior incompleto e 1,7% n\u00e3o tem instru\u00e7\u00e3o ou menos de um ano de estudo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A taxa de desemprego cresceu em 14 das 27 unidades da Federa\u00e7\u00e3o no primeiro trimestre deste ano, na compara\u00e7\u00e3o com o \u00faltimo trimestre do ano passado, segundo dados da Pesquisa Nacional por Amostra de Domic\u00edlios \u2013 Cont\u00ednua (PNAD-C), divulgada nesta quinta-feira pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Minas Gerais est\u00e1 entre os [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":244831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,4],"tags":[467,466],"class_list":["post-244830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques-1","category-lavras","tag-automatico","tag-rascunho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2019\/05\/20190516102335812042e.jpg?fit=500%2C300&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-11GS","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=244830"}],"version-history":[{"count":1,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244830\/revisions"}],"predecessor-version":[{"id":244832,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/244830\/revisions\/244832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/244831"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=244830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=244830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=244830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}