{"id":205585,"date":"2016-05-03T09:55:36","date_gmt":"2016-05-03T12:55:36","guid":{"rendered":"http:\/\/www.lavras24horas.com.br\/portal\/?p=205585"},"modified":"2016-05-03T09:57:32","modified_gmt":"2016-05-03T12:57:32","slug":"renovacao-carismatica-catolica-promovera-mega-evento-de-pentecostes-no-clube-de-lavras","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/renovacao-carismatica-catolica-promovera-mega-evento-de-pentecostes-no-clube-de-lavras\/","title":{"rendered":"Renova\u00e7\u00e3o Carism\u00e1tica Cat\u00f3lica promover\u00e1 mega evento de Pentecostes no Clube de Lavras \u00a0\u00a0  \u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A Renova\u00e7\u00e3o Carism\u00e1tica Cat\u00f3lica de Lavras (RCC) ir\u00e1 promover o \u201cEncontro de Pentecostes&#8221;, uma tarde inteira de ora\u00e7\u00e3o, louvor, anima\u00e7\u00e3o, prega\u00e7\u00f5es e Celebra\u00e7\u00e3o da Santa Missa, aberto \u00e0 todos que quiserem fazer a experi\u00eancia de um verdadeiro Cen\u00e1culo de Ora\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O evento acontecer\u00e1 no pr\u00f3ximo dia 15 de maio, domingo, a partir das 13h30, o no Clube de Lavras, pr\u00f3ximo a Pra\u00e7a Central. O tema deste ano \u00e9: &#8220;Arrependei-vos e recebereis o dom do Esp\u00edrito Santo&#8221; (At 2, 38).<\/p>\n<p style=\"text-align: justify;\">Para conduzir as prega\u00e7\u00f5es sobre o tema central, os convidados deste ano s\u00e3o: Betinho (Diocese de Santo Amaro), Fabiano Ramos (Miss\u00e3o Or\u00e1culo Santo) e Padre Reginaldo Sturin (Par\u00f3quia Santana). Haver\u00e1 venda de salgados, refrigerante e de camisetas do evento. A entrada ser\u00e1 1 kg de alimento n\u00e3o perec\u00edvel a ser doados para entidades filantr\u00f3picas da cidade de Lavras.<\/p>\n<p style=\"text-align: justify;\">A novidade para este ano e que durante o encontro, haver\u00e1 uma equipe para cuidar das crian\u00e7as enquanto os adultos participam do evento.<\/p>\n<p style=\"text-align: justify;\">Mais informa\u00e7\u00f5es podem ser obtidas atrav\u00e9s dos grupos de ora\u00e7\u00e3o da RCC das par\u00f3quias de Lavras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A Renova\u00e7\u00e3o Carism\u00e1tica Cat\u00f3lica de Lavras (RCC) ir\u00e1 promover o \u201cEncontro de Pentecostes&#8221;, uma tarde inteira de ora\u00e7\u00e3o, louvor, anima\u00e7\u00e3o, prega\u00e7\u00f5es e Celebra\u00e7\u00e3o da Santa Missa, aberto \u00e0 todos que quiserem fazer a experi\u00eancia de um verdadeiro Cen\u00e1culo de Ora\u00e7\u00e3o. O evento acontecer\u00e1 no pr\u00f3ximo dia 15 de maio, domingo, a partir das 13h30, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":205586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,4],"tags":[26241,8267,2693,1478,169,6050,543,19098,7528,16165],"class_list":["post-205585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-1","category-lavras","tag-carismatica","tag-catolica","tag-clube","tag-evento","tag-lavras-2","tag-mega","tag-no","tag-pentecostes","tag-promovera","tag-renovacao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2016\/05\/Pentecostes.jpg?fit=818%2C545&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-RtT","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/205585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=205585"}],"version-history":[{"count":0,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/205585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/205586"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=205585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=205585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=205585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}