{"id":196483,"date":"2015-09-18T20:46:10","date_gmt":"2015-09-18T23:46:10","guid":{"rendered":"http:\/\/www.lavras24horas.com.br\/portal\/?p=196483"},"modified":"2015-09-18T20:50:32","modified_gmt":"2015-09-18T23:50:32","slug":"neste-fim-de-semana-tem-mais-uma-edicao-do-playing-for-change-day-em-lavras","status":"publish","type":"post","link":"https:\/\/www.lavras24horas.com.br\/portal\/neste-fim-de-semana-tem-mais-uma-edicao-do-playing-for-change-day-em-lavras\/","title":{"rendered":"Neste fim de semana t\u00eam mais uma edi\u00e7\u00e3o do Playing For Change Day em Lavras"},"content":{"rendered":"<p>Neste s\u00e1bado e domingo , ser\u00e1 realizado em Lavras mais uma edi\u00e7\u00e3o do &#8220;Playing For Change Day&#8221;\u00a0\u00a0que\u00a0\u00a0acontece em v\u00e1rios lugares do mundo ao mesmo tempo. No ano passado aconteceu em 410 cidades, em 61 pa\u00edses, de todos os continentes. Este\u00a0\u00a0\u00e9 4\u00ba ano consecutivo que tamb\u00e9m ocorre em Lavras simultaneamente. O evento \u00e9 promovido pelo \u00a0Coletivo de Artistas RUA (Reuni\u00e3o Urbana dos Artistas de Lavras).<\/p>\n<p>O Playing For Change Day \u00e9 um evento do Playing For Change e de seus participantes do mundo inteiro, que utiliza a m\u00fasica para fazer a diferen\u00e7a em v\u00e1rios pa\u00edses, principalmente pa\u00edses em desenvolvimento. O destaque da a\u00e7\u00f5es da funda\u00e7\u00e3o \u00e9 construir escolas de m\u00fasicas com ensino gratuito e fazer com que a m\u00fasica seja uma oportunidade de mudan\u00e7a de vida. O Playing For Change Day \u00e9 acima de tudo, uma grande festa da m\u00fasica mundial.<\/p>\n<p>Em Lavras v\u00e1rios m\u00fasicos, atores, poetas e agentes culturais participar\u00e3o do evento que contar\u00e1 com dois palcos neste s\u00e1bado(19), sendo um no Jardim da Casa da Cultura e o outro na rua ao lado da Casa da Cultura (R. Desembargador Alberto Luz) e\u00a0ter\u00e1 \u00a0apresenta\u00e7\u00f5es entre 10h da manh\u00e3 e 23h e no Domingo (20) teremos apresenta\u00e7\u00f5es no coreto da P\u00e7. Dr. Augusto Silva ap\u00f3s as 9h e 30min.<\/p>\n<p>Haver\u00e1 venda de CDs dos artistas, adesivos e bebidas e todo dinheiro\u00a0ser\u00e1 doado para a Escola de M\u00fasica\u00a0de\u00a0Lavras.<\/p>\n<p>Confira a programa\u00e7\u00e3o:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"196484\" data-permalink=\"https:\/\/www.lavras24horas.com.br\/portal\/neste-fim-de-semana-tem-mais-uma-edicao-do-playing-for-change-day-em-lavras\/12041968_1691944094361540_1626077334_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg?fit=666%2C960&amp;ssl=1\" data-orig-size=\"666,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"12041968_1691944094361540_1626077334_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg?fit=228%2C330&amp;ssl=1\" class=\"aligncenter wp-image-196484 size-full\" src=\"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg?resize=666%2C960\" alt=\"12041968_1691944094361540_1626077334_n\" width=\"666\" height=\"960\" srcset=\"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg?w=666&amp;ssl=1 666w, https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/12041968_1691944094361540_1626077334_n.jpg?resize=228%2C330&amp;ssl=1 228w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>* Informa\u00e7\u00f5es retiradas da p\u00e1gina oficial do evento no Facebook.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado e domingo , ser\u00e1 realizado em Lavras mais uma edi\u00e7\u00e3o do &#8220;Playing For Change Day&#8221;\u00a0\u00a0que\u00a0\u00a0acontece em v\u00e1rios lugares do mundo ao mesmo tempo. No ano passado aconteceu em 410 cidades, em 61 pa\u00edses, de todos os continentes. Este\u00a0\u00a0\u00e9 4\u00ba ano consecutivo que tamb\u00e9m ocorre em Lavras simultaneamente. O evento \u00e9 promovido pelo \u00a0Coletivo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":196485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13077,4],"tags":[25344,15247,1077,973,22056,169,814,766,25343,767,483],"class_list":["post-196483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laterais-2","category-lavras","tag-change","tag-day","tag-edicao","tag-fim","tag-for","tag-lavras-2","tag-mais","tag-neste","tag-playing","tag-semana","tag-tem"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.lavras24horas.com.br\/portal\/wp-content\/uploads\/2015\/09\/11760120_1670553293167287_3697287332299316574_n-e1442618580997.png?fit=377%2C128&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p12djN-P75","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/196483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/comments?post=196483"}],"version-history":[{"count":0,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/posts\/196483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media\/196485"}],"wp:attachment":[{"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/media?parent=196483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/categories?post=196483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavras24horas.com.br\/portal\/wp-json\/wp\/v2\/tags?post=196483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}